{"id":1859,"date":"2024-07-19T15:30:24","date_gmt":"2024-07-19T21:30:24","guid":{"rendered":"https:\/\/lapalabra.utec.edu.sv\/?p=1859"},"modified":"2024-07-19T16:00:08","modified_gmt":"2024-07-19T22:00:08","slug":"autoridades-de-la-utec-participan-en-jornada-formativa-sobre-planeamiento-estrategico","status":"publish","type":"post","link":"https:\/\/lapalabra.utec.edu.sv\/index.php\/autoridades-de-la-utec-participan-en-jornada-formativa-sobre-planeamiento-estrategico\/","title":{"rendered":"Autoridades de la Utec participan en jornada formativa sobre planeamiento estrat\u00e9gico"},"content":{"rendered":"\n<p class=\"has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"color:#5a1533\"><strong>La apuesta principal de la misma se enfoca en establecer los lineamientos estrat\u00e9gicos de la instituci\u00f3n de cara a los pr\u00f3ximos cinco a\u00f1os.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/lapalabra.utec.edu.sv\/wp-content\/uploads\/2024\/07\/planestrategico-utec-1.mp3\"><\/audio><figcaption class=\"wp-element-caption\"><em><sub>Escuchar nota<\/sub><\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Wilber Corpe\u00f1o<br>Fotos: Alexander Morales<br>La Palabra Universitaria<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Universidad Tecnol\u00f3gica de El Salvador (Utec) ha realizado con \u00e9xito la Jornada de actualizaci\u00f3n y formaci\u00f3n-proceso de planeamiento estrat\u00e9gico 2025-2029, dirigida a decanos, directores y autoridades de la instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa, desarrollada a lo largo de cuatro intensas jornadas, tuvo como objetivo principal actualizar a los participantes en las \u00faltimas tendencias tecnol\u00f3gicas y acad\u00e9micas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento participaron autoridades de la universidad, incluyendo vicerrectores, decanos y directores de las diversas escuelas y unidades acad\u00e9micas. Cada jornada se compon\u00eda de actividades con capacitaciones y talleres especializados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el decano de la facultad de maestr\u00edas y estudios de postgrado, Juan Carlos Cerna, esta actividad se enfoca en definir la hoja de ruta estrat\u00e9gica de la Utec para los pr\u00f3ximos a\u00f1os, con el fin de alcanzar objetivos comunes y fortalecer la calidad educativa de la instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante las jornadas, los participantes pudieron explorar y discutir las recientes innovaciones en el \u00e1mbito educativo y tecnol\u00f3gico, lo que les permitir\u00e1 implementar estrategias m\u00e1s efectivas en sus \u00e1reas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cerna enfatiza que esta iniciativa no solo busca mejorar el desempe\u00f1o acad\u00e9mico y administrativo de la Utec, sino tambi\u00e9n posicionarla como una instituci\u00f3n de vanguardia en el \u00e1mbito de la educaci\u00f3n superior en El Salvador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada culmin\u00f3 con una serie de presentaciones y debates que permitieron a los asistentes compartir sus perspectivas y propuestas, consolidando as\u00ed una visi\u00f3n compartida del futuro estrat\u00e9gico de la universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El decano de maestr\u00edas puntualiz\u00f3 que, con estas acciones, la Utec reafirma su compromiso con la excelencia acad\u00e9mica y la formaci\u00f3n continua de su cuerpo docente y administrativo, asegurando un futuro prometedor y sostenible para la instituci\u00f3n y sus estudiantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La apuesta principal de la misma se enfoca en establecer los lineamientos estrat\u00e9gicos de la instituci\u00f3n de cara a los pr\u00f3ximos cinco a\u00f1os. Wilber Corpe\u00f1oFotos: Alexander MoralesLa Palabra Universitaria La Universidad Tecnol\u00f3gica de El Salvador (Utec) ha realizado con \u00e9xito la Jornada de actualizaci\u00f3n y formaci\u00f3n-proceso de planeamiento estrat\u00e9gico 2025-2029, dirigida a decanos, directores y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,6],"tags":[500,64,499],"class_list":["post-1859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campus-utec","category-en-la-academia","tag-autoridades-de-la-utec","tag-capacitacion","tag-planeamiento-estrategico"],"_links":{"self":[{"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/posts\/1859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/comments?post=1859"}],"version-history":[{"count":4,"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/posts\/1859\/revisions"}],"predecessor-version":[{"id":1898,"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/posts\/1859\/revisions\/1898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/media\/1892"}],"wp:attachment":[{"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/media?parent=1859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/categories?post=1859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lapalabra.utec.edu.sv\/index.php\/wp-json\/wp\/v2\/tags?post=1859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}